{"id":611,"date":"2020-12-21T05:12:38","date_gmt":"2020-12-21T10:12:38","guid":{"rendered":"https:\/\/research.ohioguidestone.org\/study\/?page_id=611"},"modified":"2021-01-14T12:36:25","modified_gmt":"2021-01-14T17:36:25","slug":"fathers-feelings-enrollment-form","status":"publish","type":"page","link":"https:\/\/research.ohioguidestone.org\/study\/fathers-feelings-enrollment-form\/","title":{"rendered":"Father&#8217;s Feelings Enrollment Form"},"content":{"rendered":"<div class=\"wpforms-container wpforms-container-full wpforms-container-save-resume\" id=\"wpforms-610\"><form id=\"wpforms-form-610\" class=\"wpforms-validate wpforms-form\" data-formid=\"610\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/study\/wp-json\/wp\/v2\/pages\/611\" data-token=\"4a76fa4a043ecaa23e59c85d32198d46\" data-token-time=\"1784128936\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-610-field_127-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"127\"><label class=\"wpforms-field-label\">Electronic Agreement <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_127\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_127_1\" name=\"wpforms[fields][127][]\" value=\"By checking this box, I agree to use electronic records and electronic signatures.\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_127_1\">By checking this box, I agree to use electronic records and electronic signatures.<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_2-container\" class=\"wpforms-field wpforms-field-name wpforms-one-half wpforms-first\" data-field-type=\"name\" data-field-id=\"2\"><label class=\"wpforms-field-label\">Staff name<\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-610-field_2\" class=\"wpforms-field-name-first\" name=\"wpforms[fields][2][first]\" ><label for=\"wpforms-610-field_2\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-610-field_2-last\" class=\"wpforms-field-name-last\" name=\"wpforms[fields][2][last]\" ><label for=\"wpforms-610-field_2-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><div class=\"wpforms-field-description\">For staff use only<\/div><\/div><div id=\"wpforms-610-field_5-container\" class=\"wpforms-field wpforms-field-date-time wpforms-one-half\" data-field-type=\"date-time\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_5\">Date <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-610-field_5\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-large\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][5][date]\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-610-field_6-container\" class=\"wpforms-field wpforms-field-divider\" data-field-type=\"divider\" data-field-id=\"6\"><h3 id=\"wpforms-610-field_6\">Enrollment Information<\/h3><\/div><div id=\"wpforms-610-field_7-container\" class=\"wpforms-field wpforms-field-name wpforms-one-half wpforms-first\" data-field-type=\"name\" data-field-id=\"7\"><label class=\"wpforms-field-label\">Participant name <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-610-field_7\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][7][first]\" required><label for=\"wpforms-610-field_7\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-610-field_7-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][7][last]\" required><label for=\"wpforms-610-field_7-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-610-field_8-container\" class=\"wpforms-field wpforms-field-date-time wpforms-one-half\" data-field-type=\"date-time\" data-field-id=\"8\"><label class=\"wpforms-field-label\">Participant&#039;s date of birth <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-date-dropdown-wrap wpforms-field-large\"><select name=\"wpforms[fields][8][date][m]\" id=\"wpforms-610-field_8-month\" class=\"wpforms-field-date-time-date-month wpforms-field-required\"  required><option value=\"\" class=\"placeholder\" selected disabled>MM<\/option><option value=\"1\" >1<\/option><option value=\"2\" >2<\/option><option value=\"3\" >3<\/option><option value=\"4\" >4<\/option><option value=\"5\" >5<\/option><option value=\"6\" >6<\/option><option value=\"7\" >7<\/option><option value=\"8\" >8<\/option><option value=\"9\" >9<\/option><option value=\"10\" >10<\/option><option value=\"11\" >11<\/option><option value=\"12\" >12<\/option><\/select><select name=\"wpforms[fields][8][date][d]\" id=\"wpforms-610-field_8-day\" class=\"wpforms-field-date-time-date-day wpforms-field-required\"  required><option value=\"\" class=\"placeholder\" selected disabled>DD<\/option><option value=\"1\" >1<\/option><option value=\"2\" >2<\/option><option value=\"3\" >3<\/option><option value=\"4\" >4<\/option><option value=\"5\" >5<\/option><option value=\"6\" >6<\/option><option value=\"7\" >7<\/option><option value=\"8\" >8<\/option><option value=\"9\" >9<\/option><option value=\"10\" >10<\/option><option value=\"11\" >11<\/option><option value=\"12\" >12<\/option><option value=\"13\" >13<\/option><option value=\"14\" >14<\/option><option value=\"15\" >15<\/option><option value=\"16\" >16<\/option><option value=\"17\" >17<\/option><option value=\"18\" >18<\/option><option value=\"19\" >19<\/option><option value=\"20\" >20<\/option><option value=\"21\" >21<\/option><option value=\"22\" >22<\/option><option value=\"23\" >23<\/option><option value=\"24\" >24<\/option><option value=\"25\" >25<\/option><option value=\"26\" >26<\/option><option value=\"27\" >27<\/option><option value=\"28\" >28<\/option><option value=\"29\" >29<\/option><option value=\"30\" >30<\/option><option value=\"31\" >31<\/option><\/select><select name=\"wpforms[fields][8][date][y]\" id=\"wpforms-610-field_8-year\" class=\"wpforms-field-date-time-date-year wpforms-field-required\"  required><option value=\"\" class=\"placeholder\" selected disabled>YYYY<\/option><option value=\"2027\" >2027<\/option><option value=\"2026\" >2026<\/option><option value=\"2025\" >2025<\/option><option value=\"2024\" >2024<\/option><option value=\"2023\" >2023<\/option><option value=\"2022\" >2022<\/option><option value=\"2021\" >2021<\/option><option value=\"2020\" >2020<\/option><option value=\"2019\" >2019<\/option><option value=\"2018\" >2018<\/option><option value=\"2017\" >2017<\/option><option value=\"2016\" >2016<\/option><option value=\"2015\" >2015<\/option><option value=\"2014\" >2014<\/option><option value=\"2013\" >2013<\/option><option value=\"2012\" >2012<\/option><option value=\"2011\" >2011<\/option><option value=\"2010\" >2010<\/option><option value=\"2009\" >2009<\/option><option value=\"2008\" >2008<\/option><option value=\"2007\" >2007<\/option><option value=\"2006\" >2006<\/option><option value=\"2005\" >2005<\/option><option value=\"2004\" >2004<\/option><option value=\"2003\" >2003<\/option><option value=\"2002\" >2002<\/option><option value=\"2001\" >2001<\/option><option value=\"2000\" >2000<\/option><option value=\"1999\" >1999<\/option><option value=\"1998\" >1998<\/option><option value=\"1997\" >1997<\/option><option value=\"1996\" >1996<\/option><option value=\"1995\" >1995<\/option><option value=\"1994\" >1994<\/option><option value=\"1993\" >1993<\/option><option value=\"1992\" >1992<\/option><option value=\"1991\" >1991<\/option><option value=\"1990\" >1990<\/option><option value=\"1989\" >1989<\/option><option value=\"1988\" >1988<\/option><option value=\"1987\" >1987<\/option><option value=\"1986\" >1986<\/option><option value=\"1985\" >1985<\/option><option value=\"1984\" >1984<\/option><option value=\"1983\" >1983<\/option><option value=\"1982\" >1982<\/option><option value=\"1981\" >1981<\/option><option value=\"1980\" >1980<\/option><option value=\"1979\" >1979<\/option><option value=\"1978\" >1978<\/option><option value=\"1977\" >1977<\/option><option value=\"1976\" >1976<\/option><option value=\"1975\" >1975<\/option><option value=\"1974\" >1974<\/option><option value=\"1973\" >1973<\/option><option value=\"1972\" >1972<\/option><option value=\"1971\" >1971<\/option><option value=\"1970\" >1970<\/option><option value=\"1969\" >1969<\/option><option value=\"1968\" >1968<\/option><option value=\"1967\" >1967<\/option><option value=\"1966\" >1966<\/option><option value=\"1965\" >1965<\/option><option value=\"1964\" >1964<\/option><option value=\"1963\" >1963<\/option><option value=\"1962\" >1962<\/option><option value=\"1961\" >1961<\/option><option value=\"1960\" >1960<\/option><option value=\"1959\" >1959<\/option><option value=\"1958\" >1958<\/option><option value=\"1957\" >1957<\/option><option value=\"1956\" >1956<\/option><option value=\"1955\" >1955<\/option><option value=\"1954\" >1954<\/option><option value=\"1953\" >1953<\/option><option value=\"1952\" >1952<\/option><option value=\"1951\" >1951<\/option><option value=\"1950\" >1950<\/option><option value=\"1949\" >1949<\/option><option value=\"1948\" >1948<\/option><option value=\"1947\" >1947<\/option><option value=\"1946\" >1946<\/option><option value=\"1945\" >1945<\/option><option value=\"1944\" >1944<\/option><option value=\"1943\" >1943<\/option><option value=\"1942\" >1942<\/option><option value=\"1941\" >1941<\/option><option value=\"1940\" >1940<\/option><option value=\"1939\" >1939<\/option><option value=\"1938\" >1938<\/option><option value=\"1937\" >1937<\/option><option value=\"1936\" >1936<\/option><option value=\"1935\" >1935<\/option><option value=\"1934\" >1934<\/option><option value=\"1933\" >1933<\/option><option value=\"1932\" >1932<\/option><option value=\"1931\" >1931<\/option><option value=\"1930\" >1930<\/option><option value=\"1929\" >1929<\/option><option value=\"1928\" >1928<\/option><option value=\"1927\" >1927<\/option><option value=\"1926\" >1926<\/option><option value=\"1925\" >1925<\/option><option value=\"1924\" >1924<\/option><option value=\"1923\" >1923<\/option><option value=\"1922\" >1922<\/option><option value=\"1921\" >1921<\/option><option value=\"1920\" >1920<\/option><\/select><\/div><\/div><div id=\"wpforms-610-field_9-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-first wpforms-list-inline wpforms-conditional-trigger\" data-field-type=\"radio\" data-field-id=\"9\"><label class=\"wpforms-field-label\">Is your baby born yet? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_9\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_9_1\" name=\"wpforms[fields][9]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_9_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_9_2\" name=\"wpforms[fields][9]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_9_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_10-container\" class=\"wpforms-field wpforms-field-date-time wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"date-time\" data-field-id=\"10\" style=\"display:none;\"><label class=\"wpforms-field-label\">Baby&#039;s date of birth <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-date-dropdown-wrap wpforms-field-large\"><select name=\"wpforms[fields][10][date][m]\" id=\"wpforms-610-field_10-month\" class=\"wpforms-field-date-time-date-month wpforms-field-required\"  required><option value=\"\" class=\"placeholder\" selected disabled>MM<\/option><option value=\"1\" >1<\/option><option value=\"2\" >2<\/option><option value=\"3\" >3<\/option><option value=\"4\" >4<\/option><option value=\"5\" >5<\/option><option value=\"6\" >6<\/option><option value=\"7\" >7<\/option><option value=\"8\" >8<\/option><option value=\"9\" >9<\/option><option value=\"10\" >10<\/option><option value=\"11\" >11<\/option><option value=\"12\" >12<\/option><\/select><select name=\"wpforms[fields][10][date][d]\" id=\"wpforms-610-field_10-day\" class=\"wpforms-field-date-time-date-day wpforms-field-required\"  required><option value=\"\" class=\"placeholder\" selected disabled>DD<\/option><option value=\"1\" >1<\/option><option value=\"2\" >2<\/option><option value=\"3\" >3<\/option><option value=\"4\" >4<\/option><option value=\"5\" >5<\/option><option value=\"6\" >6<\/option><option value=\"7\" >7<\/option><option value=\"8\" >8<\/option><option value=\"9\" >9<\/option><option value=\"10\" >10<\/option><option value=\"11\" >11<\/option><option value=\"12\" >12<\/option><option value=\"13\" >13<\/option><option value=\"14\" >14<\/option><option value=\"15\" >15<\/option><option value=\"16\" >16<\/option><option value=\"17\" >17<\/option><option value=\"18\" >18<\/option><option value=\"19\" >19<\/option><option value=\"20\" >20<\/option><option value=\"21\" >21<\/option><option value=\"22\" >22<\/option><option value=\"23\" >23<\/option><option value=\"24\" >24<\/option><option value=\"25\" >25<\/option><option value=\"26\" >26<\/option><option value=\"27\" >27<\/option><option value=\"28\" >28<\/option><option value=\"29\" >29<\/option><option value=\"30\" >30<\/option><option value=\"31\" >31<\/option><\/select><select name=\"wpforms[fields][10][date][y]\" id=\"wpforms-610-field_10-year\" class=\"wpforms-field-date-time-date-year wpforms-field-required\"  required><option value=\"\" class=\"placeholder\" selected disabled>YYYY<\/option><option value=\"2027\" >2027<\/option><option value=\"2026\" >2026<\/option><option value=\"2025\" >2025<\/option><option value=\"2024\" >2024<\/option><option value=\"2023\" >2023<\/option><option value=\"2022\" >2022<\/option><option value=\"2021\" >2021<\/option><option value=\"2020\" >2020<\/option><option value=\"2019\" >2019<\/option><option value=\"2018\" >2018<\/option><option value=\"2017\" >2017<\/option><option value=\"2016\" >2016<\/option><option value=\"2015\" >2015<\/option><option value=\"2014\" >2014<\/option><option value=\"2013\" >2013<\/option><option value=\"2012\" >2012<\/option><option value=\"2011\" >2011<\/option><option value=\"2010\" >2010<\/option><option value=\"2009\" >2009<\/option><option value=\"2008\" >2008<\/option><option value=\"2007\" >2007<\/option><option value=\"2006\" >2006<\/option><option value=\"2005\" >2005<\/option><option value=\"2004\" >2004<\/option><option value=\"2003\" >2003<\/option><option value=\"2002\" >2002<\/option><option value=\"2001\" >2001<\/option><option value=\"2000\" >2000<\/option><option value=\"1999\" >1999<\/option><option value=\"1998\" >1998<\/option><option value=\"1997\" >1997<\/option><option value=\"1996\" >1996<\/option><option value=\"1995\" >1995<\/option><option value=\"1994\" >1994<\/option><option value=\"1993\" >1993<\/option><option value=\"1992\" >1992<\/option><option value=\"1991\" >1991<\/option><option value=\"1990\" >1990<\/option><option value=\"1989\" >1989<\/option><option value=\"1988\" >1988<\/option><option value=\"1987\" >1987<\/option><option value=\"1986\" >1986<\/option><option value=\"1985\" >1985<\/option><option value=\"1984\" >1984<\/option><option value=\"1983\" >1983<\/option><option value=\"1982\" >1982<\/option><option value=\"1981\" >1981<\/option><option value=\"1980\" >1980<\/option><option value=\"1979\" >1979<\/option><option value=\"1978\" >1978<\/option><option value=\"1977\" >1977<\/option><option value=\"1976\" >1976<\/option><option value=\"1975\" >1975<\/option><option value=\"1974\" >1974<\/option><option value=\"1973\" >1973<\/option><option value=\"1972\" >1972<\/option><option value=\"1971\" >1971<\/option><option value=\"1970\" >1970<\/option><option value=\"1969\" >1969<\/option><option value=\"1968\" >1968<\/option><option value=\"1967\" >1967<\/option><option value=\"1966\" >1966<\/option><option value=\"1965\" >1965<\/option><option value=\"1964\" >1964<\/option><option value=\"1963\" >1963<\/option><option value=\"1962\" >1962<\/option><option value=\"1961\" >1961<\/option><option value=\"1960\" >1960<\/option><option value=\"1959\" >1959<\/option><option value=\"1958\" >1958<\/option><option value=\"1957\" >1957<\/option><option value=\"1956\" >1956<\/option><option value=\"1955\" >1955<\/option><option value=\"1954\" >1954<\/option><option value=\"1953\" >1953<\/option><option value=\"1952\" >1952<\/option><option value=\"1951\" >1951<\/option><option value=\"1950\" >1950<\/option><option value=\"1949\" >1949<\/option><option value=\"1948\" >1948<\/option><option value=\"1947\" >1947<\/option><option value=\"1946\" >1946<\/option><option value=\"1945\" >1945<\/option><option value=\"1944\" >1944<\/option><option value=\"1943\" >1943<\/option><option value=\"1942\" >1942<\/option><option value=\"1941\" >1941<\/option><option value=\"1940\" >1940<\/option><option value=\"1939\" >1939<\/option><option value=\"1938\" >1938<\/option><option value=\"1937\" >1937<\/option><option value=\"1936\" >1936<\/option><option value=\"1935\" >1935<\/option><option value=\"1934\" >1934<\/option><option value=\"1933\" >1933<\/option><option value=\"1932\" >1932<\/option><option value=\"1931\" >1931<\/option><option value=\"1930\" >1930<\/option><option value=\"1929\" >1929<\/option><option value=\"1928\" >1928<\/option><option value=\"1927\" >1927<\/option><option value=\"1926\" >1926<\/option><option value=\"1925\" >1925<\/option><option value=\"1924\" >1924<\/option><option value=\"1923\" >1923<\/option><option value=\"1922\" >1922<\/option><option value=\"1921\" >1921<\/option><option value=\"1920\" >1920<\/option><\/select><\/div><\/div><div id=\"wpforms-610-field_11-container\" class=\"wpforms-field wpforms-field-date-time wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"date-time\" data-field-id=\"11\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_11\">Baby&#039;s estimated due date <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-610-field_11\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-large\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"1\" data-disable-todays-date=\"0\" data-input=\"true\" name=\"wpforms[fields][11][date]\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-610-field_12-container\" class=\"wpforms-field wpforms-field-address\" data-field-type=\"address\" data-field-id=\"12\"><label class=\"wpforms-field-label\">Address <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div ><input type=\"text\" id=\"wpforms-610-field_12\" class=\"wpforms-field-address-address1 wpforms-field-required\" name=\"wpforms[fields][12][address1]\" required><label for=\"wpforms-610-field_12\" class=\"wpforms-field-sublabel after\">Address Line 1<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div ><input type=\"text\" id=\"wpforms-610-field_12-address2\" class=\"wpforms-field-address-address2\" name=\"wpforms[fields][12][address2]\" ><label for=\"wpforms-610-field_12-address2\" class=\"wpforms-field-sublabel after\">Address Line 2<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-610-field_12-city\" class=\"wpforms-field-address-city wpforms-field-required\" name=\"wpforms[fields][12][city]\" required><label for=\"wpforms-610-field_12-city\" class=\"wpforms-field-sublabel after\">City<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><select id=\"wpforms-610-field_12-state\" class=\"wpforms-field-address-state wpforms-field-required\" name=\"wpforms[fields][12][state]\" required><option value=\"AL\" >Alabama<\/option><option value=\"AK\" >Alaska<\/option><option value=\"AZ\" >Arizona<\/option><option value=\"AR\" >Arkansas<\/option><option value=\"CA\" >California<\/option><option value=\"CO\" >Colorado<\/option><option value=\"CT\" >Connecticut<\/option><option value=\"DE\" >Delaware<\/option><option value=\"DC\" >District of Columbia<\/option><option value=\"FL\" >Florida<\/option><option value=\"GA\" >Georgia<\/option><option value=\"HI\" >Hawaii<\/option><option value=\"ID\" >Idaho<\/option><option value=\"IL\" >Illinois<\/option><option value=\"IN\" >Indiana<\/option><option value=\"IA\" >Iowa<\/option><option value=\"KS\" >Kansas<\/option><option value=\"KY\" >Kentucky<\/option><option value=\"LA\" >Louisiana<\/option><option value=\"ME\" >Maine<\/option><option value=\"MD\" >Maryland<\/option><option value=\"MA\" >Massachusetts<\/option><option value=\"MI\" >Michigan<\/option><option value=\"MN\" >Minnesota<\/option><option value=\"MS\" >Mississippi<\/option><option value=\"MO\" >Missouri<\/option><option value=\"MT\" >Montana<\/option><option value=\"NE\" >Nebraska<\/option><option value=\"NV\" >Nevada<\/option><option value=\"NH\" >New Hampshire<\/option><option value=\"NJ\" >New Jersey<\/option><option value=\"NM\" >New Mexico<\/option><option value=\"NY\" >New York<\/option><option value=\"NC\" >North Carolina<\/option><option value=\"ND\" >North Dakota<\/option><option value=\"OH\"  selected='selected'>Ohio<\/option><option value=\"OK\" >Oklahoma<\/option><option value=\"OR\" >Oregon<\/option><option value=\"PA\" >Pennsylvania<\/option><option value=\"RI\" >Rhode Island<\/option><option value=\"SC\" >South Carolina<\/option><option value=\"SD\" >South Dakota<\/option><option value=\"TN\" >Tennessee<\/option><option value=\"TX\" >Texas<\/option><option value=\"UT\" >Utah<\/option><option value=\"VT\" >Vermont<\/option><option value=\"VA\" >Virginia<\/option><option value=\"WA\" >Washington<\/option><option value=\"WV\" >West Virginia<\/option><option value=\"WI\" >Wisconsin<\/option><option value=\"WY\" >Wyoming<\/option><\/select><label for=\"wpforms-610-field_12-state\" class=\"wpforms-field-sublabel after\">State<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-610-field_12-postal\" class=\"wpforms-field-address-postal wpforms-field-required wpforms-masked-input\" data-inputmask-mask=\"(99999)|(99999-9999)\" data-inputmask-keepstatic=\"true\" data-rule-inputmask-incomplete=\"1\" name=\"wpforms[fields][12][postal]\" required><label for=\"wpforms-610-field_12-postal\" class=\"wpforms-field-sublabel after\">Zip Code<\/label><\/div><\/div><\/div><div id=\"wpforms-610-field_13-container\" class=\"wpforms-field wpforms-field-email wpforms-one-half wpforms-first\" data-field-type=\"email\" data-field-id=\"13\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_13\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-610-field_13\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][13]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-610-field_14-container\" class=\"wpforms-field wpforms-field-phone wpforms-one-half\" data-field-type=\"phone\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_14\">Phone number <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-610-field_14\" class=\"wpforms-field-large wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][14]\" aria-label=\"Phone number\" required><\/div><div id=\"wpforms-610-field_128-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-half wpforms-first wpforms-list-inline\" data-field-type=\"checkbox\" data-field-id=\"128\"><label class=\"wpforms-field-label\">I give permission for study staff to text me regarding study appointments at the above phone number <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_128\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_128_1\" name=\"wpforms[fields][128][]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_128_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_128_2\" name=\"wpforms[fields][128][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_128_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_129-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-half wpforms-list-inline\" data-field-type=\"checkbox\" data-field-id=\"129\"><label class=\"wpforms-field-label\">I give permission for study staff to leave me voicemails regarding study appointments at the above phone number <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_129\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_129_1\" name=\"wpforms[fields][129][]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_129_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_129_2\" name=\"wpforms[fields][129][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_129_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_15-container\" class=\"wpforms-field wpforms-field-name wpforms-one-half wpforms-first\" data-field-type=\"name\" data-field-id=\"15\"><label class=\"wpforms-field-label\">Emergency contact<\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-610-field_15\" class=\"wpforms-field-name-first\" name=\"wpforms[fields][15][first]\" ><label for=\"wpforms-610-field_15\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-610-field_15-last\" class=\"wpforms-field-name-last\" name=\"wpforms[fields][15][last]\" ><label for=\"wpforms-610-field_15-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-610-field_16-container\" class=\"wpforms-field wpforms-field-phone wpforms-one-half\" data-field-type=\"phone\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_16\">Emergency contact number<\/label><input type=\"tel\" id=\"wpforms-610-field_16\" class=\"wpforms-field-large wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][16]\" aria-label=\"Emergency contact number\" ><\/div><div id=\"wpforms-610-field_19-container\" class=\"wpforms-field wpforms-field-divider\" data-field-type=\"divider\" data-field-id=\"19\"><h3 id=\"wpforms-610-field_19\">Demographic Information<\/h3><\/div><div id=\"wpforms-610-field_20-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-first\" data-field-type=\"text\" data-field-id=\"20\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_20\">Primary language spoken at home <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_20\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][20]\" required><\/div><div id=\"wpforms-610-field_21-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-half wpforms-list-inline\" data-field-type=\"radio\" data-field-id=\"21\"><label class=\"wpforms-field-label\">Are you of Hispanic\/Latinx heritage? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_21\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_21_1\" name=\"wpforms[fields][21]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_21_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_21_2\" name=\"wpforms[fields][21]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_21_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_22-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-two-thirds wpforms-first wpforms-list-2-columns wpforms-conditional-trigger\" data-field-type=\"checkbox\" data-field-id=\"22\"><label class=\"wpforms-field-label\">Race (please choose all that apply) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_22\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_22_1\" name=\"wpforms[fields][22][]\" value=\"Native American\/Alaskan Native\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_22_1\">Native American\/Alaskan Native<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_22_2\" name=\"wpforms[fields][22][]\" value=\"Asian\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_22_2\">Asian<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_22_3\" name=\"wpforms[fields][22][]\" value=\"African American\/Black\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_22_3\">African American\/Black<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_22_4\" name=\"wpforms[fields][22][]\" value=\"Caucasian\/White\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_22_4\">Caucasian\/White<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_22_5\" name=\"wpforms[fields][22][]\" value=\"Native Hawaiian\/Pacific Islander\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_22_5\">Native Hawaiian\/Pacific Islander<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_22_6\" name=\"wpforms[fields][22][]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_22_6\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_23-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"23\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_23\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_23\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][23]\" required><\/div><div id=\"wpforms-610-field_24-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-half wpforms-first wpforms-list-3-columns wpforms-conditional-trigger\" data-field-type=\"radio\" data-field-id=\"24\"><label class=\"wpforms-field-label\">Relationship status <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_24\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_24_1\" name=\"wpforms[fields][24]\" value=\"Married\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_24_1\">Married<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_24_2\" name=\"wpforms[fields][24]\" value=\"Partnered\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_24_2\">Partnered<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_24_3\" name=\"wpforms[fields][24]\" value=\"Single\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_24_3\">Single<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_24_4\" name=\"wpforms[fields][24]\" value=\"Divorced\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_24_4\">Divorced<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_24_5\" name=\"wpforms[fields][24]\" value=\"Widowed\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_24_5\">Widowed<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_24_6\" name=\"wpforms[fields][24]\" value=\"Separated\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_24_6\">Separated<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_25-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-half wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"25\" style=\"display:none;\"><label class=\"wpforms-field-label\">Are you married to the mother of your baby? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_25\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_25_1\" name=\"wpforms[fields][25]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_25_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_25_2\" name=\"wpforms[fields][25]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_25_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_26-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-half wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"26\" style=\"display:none;\"><label class=\"wpforms-field-label\">Are you partnered to the mother of your baby? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_26\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_26_1\" name=\"wpforms[fields][26]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_26_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_26_2\" name=\"wpforms[fields][26]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_26_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_27-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-half wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"27\" style=\"display:none;\"><label class=\"wpforms-field-label\">Are you divorced from the mother of your baby? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_27\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_27_1\" name=\"wpforms[fields][27]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_27_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_27_2\" name=\"wpforms[fields][27]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_27_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_126-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-half wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"126\" style=\"display:none;\"><label class=\"wpforms-field-label\">Are you widowed from the mother of your baby? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_126\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_126_1\" name=\"wpforms[fields][126]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_126_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_126_2\" name=\"wpforms[fields][126]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_126_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_28-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-half wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"28\" style=\"display:none;\"><label class=\"wpforms-field-label\">Are you separated from the mother of your baby? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_28\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_28_1\" name=\"wpforms[fields][28]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_28_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_28_2\" name=\"wpforms[fields][28]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_28_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_29-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-half wpforms-first wpforms-list-2-columns wpforms-conditional-trigger\" data-field-type=\"radio\" data-field-id=\"29\"><label class=\"wpforms-field-label\">Education level <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_29\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_29_1\" name=\"wpforms[fields][29]\" value=\"High school diploma\/GED\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_29_1\">High school diploma\/GED<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_29_2\" name=\"wpforms[fields][29]\" value=\"Trade school\/vocational training\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_29_2\">Trade school\/vocational training<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_29_3\" name=\"wpforms[fields][29]\" value=\"Some college\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_29_3\">Some college<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_29_4\" name=\"wpforms[fields][29]\" value=\"2-year college degree (associate&#039;s)\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_29_4\">2-year college degree (associate's)<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_29_5\" name=\"wpforms[fields][29]\" value=\"4-year college degree (bachelor&#039;s)\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_29_5\">4-year college degree (bachelor's)<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_29_6\" name=\"wpforms[fields][29]\" value=\"Master&#039;s degree\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_29_6\">Master's degree<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_29_7\" name=\"wpforms[fields][29]\" value=\"PhD or advanced degree\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_29_7\">PhD or advanced degree<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_29_8\" name=\"wpforms[fields][29]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_29_8\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_30-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"30\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_30\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_30\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][30]\" required><\/div><div id=\"wpforms-610-field_31-container\" class=\"wpforms-field wpforms-field-divider\" data-field-type=\"divider\" data-field-id=\"31\"><h3 id=\"wpforms-610-field_31\">Household Information<\/h3><\/div><div id=\"wpforms-610-field_32-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-type=\"radio\" data-field-id=\"32\"><label class=\"wpforms-field-label\">Annual household income <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_32\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_32_1\" name=\"wpforms[fields][32]\" value=\"Below $5,000\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_32_1\">Below $5,000<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_32_2\" name=\"wpforms[fields][32]\" value=\"$5,000 to $14,999\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_32_2\">$5,000 to $14,999<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_32_3\" name=\"wpforms[fields][32]\" value=\"$15,000 to $24,999\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_32_3\">$15,000 to $24,999<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_32_4\" name=\"wpforms[fields][32]\" value=\"$25,000 to $34,999\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_32_4\">$25,000 to $34,999<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_32_5\" name=\"wpforms[fields][32]\" value=\"$35,000 to $49,999\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_32_5\">$35,000 to $49,999<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_32_6\" name=\"wpforms[fields][32]\" value=\"$50,000 to $74,999\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_32_6\">$50,000 to $74,999<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_32_7\" name=\"wpforms[fields][32]\" value=\"$75,000 to $99,999\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_32_7\">$75,000 to $99,999<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_32_8\" name=\"wpforms[fields][32]\" value=\"$100,000 to $149,999\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_32_8\">$100,000 to $149,999<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_32_9\" name=\"wpforms[fields][32]\" value=\"$150,000 to $199,999\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_32_9\">$150,000 to $199,999<\/label><\/li><li class=\"choice-10 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_32_10\" name=\"wpforms[fields][32]\" value=\"$200,000 or more\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_32_10\">$200,000 or more<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_33-container\" class=\"wpforms-field wpforms-field-radio wpforms-two-thirds wpforms-first wpforms-list-3-columns wpforms-conditional-trigger\" data-field-type=\"radio\" data-field-id=\"33\"><label class=\"wpforms-field-label\">Employment status <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_33\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_33_1\" name=\"wpforms[fields][33]\" value=\"Employed outside of the home\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_33_1\">Employed outside of the home<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_33_2\" name=\"wpforms[fields][33]\" value=\"Self-employed\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_33_2\">Self-employed<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_33_3\" name=\"wpforms[fields][33]\" value=\"Out of work\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_33_3\">Out of work<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_33_4\" name=\"wpforms[fields][33]\" value=\"Homemaker\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_33_4\">Homemaker<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_33_5\" name=\"wpforms[fields][33]\" value=\"Student\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_33_5\">Student<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_33_6\" name=\"wpforms[fields][33]\" value=\"Retired\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_33_6\">Retired<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_33_7\" name=\"wpforms[fields][33]\" value=\"Unable to work\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_33_7\">Unable to work<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_33_8\" name=\"wpforms[fields][33]\" value=\"Military\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_33_8\">Military<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_33_9\" name=\"wpforms[fields][33]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_33_9\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_34-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"34\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_34\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_34\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][34]\" required><\/div><div id=\"wpforms-610-field_36-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"36\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_36\">Occupation\/job <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_36\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][36]\" required><\/div><div id=\"wpforms-610-field_35-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-type=\"radio\" data-field-id=\"35\"><label class=\"wpforms-field-label\">Are or were you and\/or your partner in the military? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_35\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_35_1\" name=\"wpforms[fields][35]\" value=\"Yes, only me\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_35_1\">Yes, only me<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_35_2\" name=\"wpforms[fields][35]\" value=\"Yes, only my partner\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_35_2\">Yes, only my partner<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_35_3\" name=\"wpforms[fields][35]\" value=\"Yes, both me and my partner\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_35_3\">Yes, both me and my partner<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_35_4\" name=\"wpforms[fields][35]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_35_4\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_38-container\" class=\"wpforms-field wpforms-field-number wpforms-one-third wpforms-first\" data-field-type=\"number\" data-field-id=\"38\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_38\">Household family size (includes you, other adults, and children) <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-610-field_38\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][38]\" step=\"any\" required><\/div><div id=\"wpforms-610-field_39-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-list-inline\" data-field-type=\"radio\" data-field-id=\"39\"><label class=\"wpforms-field-label\">Is the mother of your baby included in your household? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_39\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_39_1\" name=\"wpforms[fields][39]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_39_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_39_2\" name=\"wpforms[fields][39]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_39_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_40-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-list-inline\" data-field-type=\"radio\" data-field-id=\"40\"><label class=\"wpforms-field-label\">Is your partner currently pregnant? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_40\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_40_1\" name=\"wpforms[fields][40]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_40_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_40_2\" name=\"wpforms[fields][40]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_40_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_41-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-type=\"radio\" data-field-id=\"41\"><label class=\"wpforms-field-label\">Family housing situation <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_41\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_41_1\" name=\"wpforms[fields][41]\" value=\"Own\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_41_1\">Own<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_41_2\" name=\"wpforms[fields][41]\" value=\"Rent\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_41_2\">Rent<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_41_3\" name=\"wpforms[fields][41]\" value=\"Permanent shared housing with relatives or friends\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_41_3\">Permanent shared housing with relatives or friends<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_41_4\" name=\"wpforms[fields][41]\" value=\"Temporary (shelter; temporarily with relatives or friends)\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_41_4\">Temporary (shelter; temporarily with relatives or friends)<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_41_5\" name=\"wpforms[fields][41]\" value=\"Homeless\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_41_5\">Homeless<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_42-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-half wpforms-first wpforms-list-2-columns wpforms-conditional-trigger\" data-field-type=\"radio\" data-field-id=\"42\"><label class=\"wpforms-field-label\">Who do you co-parent with? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_42\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_42_1\" name=\"wpforms[fields][42]\" value=\"No one\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_42_1\">No one<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_42_2\" name=\"wpforms[fields][42]\" value=\"Husband\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_42_2\">Husband<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_42_3\" name=\"wpforms[fields][42]\" value=\"Wife\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_42_3\">Wife<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_42_8\" name=\"wpforms[fields][42]\" value=\"Partner\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_42_8\">Partner<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_42_4\" name=\"wpforms[fields][42]\" value=\"Sister\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_42_4\">Sister<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_42_5\" name=\"wpforms[fields][42]\" value=\"Brother\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_42_5\">Brother<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_42_6\" name=\"wpforms[fields][42]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_42_6\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_43-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"43\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_43\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_43\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][43]\" required><\/div><div id=\"wpforms-610-field_44-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"44\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_44\">My co-parent&#039;s relationship to my child(ren) is <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_44\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][44]\" placeholder=\"Mother\" required><div class=\"wpforms-field-description\">Examples: Mother, Father, Stepmother, Dad's girlfriend, Mom's partner, Grandmother, Aunt, Foster mother, etc.<\/div><\/div><div id=\"wpforms-610-field_45-container\" class=\"wpforms-field wpforms-field-divider\" data-field-type=\"divider\" data-field-id=\"45\"><h3 id=\"wpforms-610-field_45\">Demographics of Children<\/h3><\/div><div id=\"wpforms-610-field_52-container\" class=\"wpforms-field wpforms-field-number-slider wpforms-conditional-trigger\" data-field-type=\"number-slider\" data-field-id=\"52\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_52\">How many children do you have?<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-610-field_52\" class=\"wpforms-field-small\" name=\"wpforms[fields][52]\" value=\"0\"\t\tmin=\"0\"\n\tmax=\"8\"\n\tstep=\"1\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"Number of children: {value}\">\n\tNumber of children: <b>0<\/b><\/div>\n<\/div><div id=\"wpforms-610-field_59-container\" class=\"wpforms-field wpforms-field-divider wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"divider\" data-field-id=\"59\" style=\"display:none;\"><h3 id=\"wpforms-610-field_59\">Child 1<\/h3><\/div><div id=\"wpforms-610-field_51-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-first wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"51\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_51\">Child 1&#039;s age <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_51\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][51]\" placeholder=\"e.g., 6 months, 4 years, 3 weeks\" required><\/div><div id=\"wpforms-610-field_53-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"53\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_53\">Child 1&#039;s gender <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_53\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][53]\" required><\/div><div id=\"wpforms-610-field_54-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"54\" style=\"display:none;\"><label class=\"wpforms-field-label\">Does child 1 live with you? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_54\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_54_1\" name=\"wpforms[fields][54]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_54_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_54_2\" name=\"wpforms[fields][54]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_54_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_56-container\" class=\"wpforms-field wpforms-field-radio wpforms-two-thirds wpforms-first wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"radio\" data-field-id=\"56\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 1&#039;s relationship to you <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_56\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_56_1\" name=\"wpforms[fields][56]\" value=\"Biological child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_56_1\">Biological child<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_56_2\" name=\"wpforms[fields][56]\" value=\"Stepchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_56_2\">Stepchild<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_56_4\" name=\"wpforms[fields][56]\" value=\"Adopted child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_56_4\">Adopted child<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_56_5\" name=\"wpforms[fields][56]\" value=\"Grandchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_56_5\">Grandchild<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_56_6\" name=\"wpforms[fields][56]\" value=\"Sibling\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_56_6\">Sibling<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_56_7\" name=\"wpforms[fields][56]\" value=\"Niece\/newphew\/cousin\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_56_7\">Niece\/nephew\/cousin<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_56_8\" name=\"wpforms[fields][56]\" value=\"Foster child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_56_8\">Foster child<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_56_9\" name=\"wpforms[fields][56]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_56_9\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_57-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"57\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_57\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_57\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][57]\" required><\/div><div id=\"wpforms-610-field_65-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-first wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"65\" style=\"display:none;\"><label class=\"wpforms-field-label\">Is child 1 of Hispanic\/Latinx heritage? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_65\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_65_1\" name=\"wpforms[fields][65]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_65_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_65_2\" name=\"wpforms[fields][65]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_65_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_66-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-third wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"checkbox\" data-field-id=\"66\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 1&#039;s race (please choose all that apply) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_66\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_66_1\" name=\"wpforms[fields][66][]\" value=\"Native American\/Alaskan Native\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_66_1\">Native American\/Alaskan Native<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_66_2\" name=\"wpforms[fields][66][]\" value=\"Asian\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_66_2\">Asian<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_66_3\" name=\"wpforms[fields][66][]\" value=\"African American\/Black\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_66_3\">African American\/Black<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_66_4\" name=\"wpforms[fields][66][]\" value=\"Caucasian\/White\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_66_4\">Caucasian\/White<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_66_5\" name=\"wpforms[fields][66][]\" value=\"Native Hawaiian\/Pacific Islander\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_66_5\">Native Hawaiian\/Pacific Islander<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_66_6\" name=\"wpforms[fields][66][]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_66_6\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_71-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"71\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_71\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_71\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][71]\" required><\/div><div id=\"wpforms-610-field_60-container\" class=\"wpforms-field wpforms-field-divider wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"divider\" data-field-id=\"60\" style=\"display:none;\"><h3 id=\"wpforms-610-field_60\">Child 2<\/h3><\/div><div id=\"wpforms-610-field_61-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-first wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"61\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_61\">Child 2&#039;s age <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_61\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][61]\" placeholder=\"e.g., 6 months, 4 years, 3 weeks\" required><\/div><div id=\"wpforms-610-field_62-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"62\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_62\">Child 2&#039;s gender <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_62\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][62]\" required><\/div><div id=\"wpforms-610-field_63-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"63\" style=\"display:none;\"><label class=\"wpforms-field-label\">Does child 2 live with you? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_63\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_63_1\" name=\"wpforms[fields][63]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_63_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_63_2\" name=\"wpforms[fields][63]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_63_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_64-container\" class=\"wpforms-field wpforms-field-radio wpforms-two-thirds wpforms-first wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"radio\" data-field-id=\"64\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 2&#039;s relationship to you <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_64\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_64_1\" name=\"wpforms[fields][64]\" value=\"Biological child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_64_1\">Biological child<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_64_2\" name=\"wpforms[fields][64]\" value=\"Stepchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_64_2\">Stepchild<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_64_4\" name=\"wpforms[fields][64]\" value=\"Adopted child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_64_4\">Adopted child<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_64_5\" name=\"wpforms[fields][64]\" value=\"Grandchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_64_5\">Grandchild<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_64_6\" name=\"wpforms[fields][64]\" value=\"Sibling\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_64_6\">Sibling<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_64_7\" name=\"wpforms[fields][64]\" value=\"Niece\/nephew\/cousin\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_64_7\">Niece\/nephew\/cousin<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_64_8\" name=\"wpforms[fields][64]\" value=\"Foster child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_64_8\">Foster child<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_64_9\" name=\"wpforms[fields][64]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_64_9\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_68-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"68\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_68\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_68\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][68]\" required><\/div><div id=\"wpforms-610-field_67-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-first wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"67\" style=\"display:none;\"><label class=\"wpforms-field-label\">Is child 2 of Hispanic\/Latinx heritage? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_67\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_67_1\" name=\"wpforms[fields][67]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_67_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_67_2\" name=\"wpforms[fields][67]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_67_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_69-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-third wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"checkbox\" data-field-id=\"69\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 2&#039;s race (please choose all that apply) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_69\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_69_1\" name=\"wpforms[fields][69][]\" value=\"Native American\/Alaskan Native\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_69_1\">Native American\/Alaskan Native<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_69_2\" name=\"wpforms[fields][69][]\" value=\"Asian\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_69_2\">Asian<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_69_3\" name=\"wpforms[fields][69][]\" value=\"African American\/Black\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_69_3\">African American\/Black<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_69_4\" name=\"wpforms[fields][69][]\" value=\"Caucasian\/White\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_69_4\">Caucasian\/White<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_69_5\" name=\"wpforms[fields][69][]\" value=\"Native Hawaiian\/Pacific Islander\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_69_5\">Native Hawaiian\/Pacific Islander<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_69_6\" name=\"wpforms[fields][69][]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_69_6\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_70-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"70\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_70\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_70\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][70]\" required><\/div><div id=\"wpforms-610-field_72-container\" class=\"wpforms-field wpforms-field-divider wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"divider\" data-field-id=\"72\" style=\"display:none;\"><h3 id=\"wpforms-610-field_72\">Child 3<\/h3><\/div><div id=\"wpforms-610-field_73-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-first wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"73\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_73\">Child 3&#039;s age <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_73\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][73]\" placeholder=\"e.g., 6 months, 4 years, 3 weeks\" required><\/div><div id=\"wpforms-610-field_74-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"74\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_74\">Child 3&#039;s gender <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_74\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][74]\" required><\/div><div id=\"wpforms-610-field_75-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"75\" style=\"display:none;\"><label class=\"wpforms-field-label\">Does child 3 live with you? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_75\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_75_1\" name=\"wpforms[fields][75]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_75_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_75_2\" name=\"wpforms[fields][75]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_75_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_76-container\" class=\"wpforms-field wpforms-field-radio wpforms-two-thirds wpforms-first wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"radio\" data-field-id=\"76\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 3&#039;s relationship to you <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_76\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_76_1\" name=\"wpforms[fields][76]\" value=\"Biological child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_76_1\">Biological child<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_76_2\" name=\"wpforms[fields][76]\" value=\"Stepchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_76_2\">Stepchild<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_76_4\" name=\"wpforms[fields][76]\" value=\"Adopted child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_76_4\">Adopted child<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_76_5\" name=\"wpforms[fields][76]\" value=\"Grandchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_76_5\">Grandchild<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_76_6\" name=\"wpforms[fields][76]\" value=\"Sibling\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_76_6\">Sibling<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_76_7\" name=\"wpforms[fields][76]\" value=\"Niece\/nephew\/cousin\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_76_7\">Niece\/nephew\/cousin<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_76_8\" name=\"wpforms[fields][76]\" value=\"Foster child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_76_8\">Foster child<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_76_9\" name=\"wpforms[fields][76]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_76_9\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_77-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"77\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_77\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_77\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][77]\" required><\/div><div id=\"wpforms-610-field_78-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-first wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"78\" style=\"display:none;\"><label class=\"wpforms-field-label\">Is child 3 of Hispanic\/Latinx heritage? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_78\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_78_1\" name=\"wpforms[fields][78]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_78_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_78_2\" name=\"wpforms[fields][78]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_78_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_79-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-third wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"checkbox\" data-field-id=\"79\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 3&#039;s race (please choose all that apply) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_79\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_79_1\" name=\"wpforms[fields][79][]\" value=\"Native American\/Alaskan Native\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_79_1\">Native American\/Alaskan Native<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_79_2\" name=\"wpforms[fields][79][]\" value=\"Asian\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_79_2\">Asian<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_79_3\" name=\"wpforms[fields][79][]\" value=\"African American\/Black\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_79_3\">African American\/Black<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_79_4\" name=\"wpforms[fields][79][]\" value=\"Caucasian\/White\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_79_4\">Caucasian\/White<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_79_5\" name=\"wpforms[fields][79][]\" value=\"Native Hawaiian\/Pacific Islander\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_79_5\">Native Hawaiian\/Pacific Islander<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_79_6\" name=\"wpforms[fields][79][]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_79_6\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_80-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"80\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_80\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_80\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][80]\" required><\/div><div id=\"wpforms-610-field_81-container\" class=\"wpforms-field wpforms-field-divider wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"divider\" data-field-id=\"81\" style=\"display:none;\"><h3 id=\"wpforms-610-field_81\">Child 4<\/h3><\/div><div id=\"wpforms-610-field_82-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-first wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"82\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_82\">Child 4&#039;s age <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_82\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][82]\" placeholder=\"e.g., 6 months, 4 years, 3 weeks\" required><\/div><div id=\"wpforms-610-field_83-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"83\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_83\">Child 4&#039;s gender <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_83\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][83]\" required><\/div><div id=\"wpforms-610-field_84-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"84\" style=\"display:none;\"><label class=\"wpforms-field-label\">Does child 4 live with you? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_84\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_84_1\" name=\"wpforms[fields][84]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_84_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_84_2\" name=\"wpforms[fields][84]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_84_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_85-container\" class=\"wpforms-field wpforms-field-radio wpforms-two-thirds wpforms-first wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"radio\" data-field-id=\"85\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 4&#039;s relationship to you <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_85\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_85_1\" name=\"wpforms[fields][85]\" value=\"Biological child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_85_1\">Biological child<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_85_2\" name=\"wpforms[fields][85]\" value=\"Stepchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_85_2\">Stepchild<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_85_4\" name=\"wpforms[fields][85]\" value=\"Adopted child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_85_4\">Adopted child<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_85_5\" name=\"wpforms[fields][85]\" value=\"Grandchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_85_5\">Grandchild<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_85_6\" name=\"wpforms[fields][85]\" value=\"Sibling\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_85_6\">Sibling<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_85_7\" name=\"wpforms[fields][85]\" value=\"Niece\/nephew\/cousin\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_85_7\">Niece\/nephew\/cousin<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_85_8\" name=\"wpforms[fields][85]\" value=\"Foster child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_85_8\">Foster child<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_85_9\" name=\"wpforms[fields][85]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_85_9\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_86-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"86\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_86\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_86\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][86]\" required><\/div><div id=\"wpforms-610-field_96-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-first wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"96\" style=\"display:none;\"><label class=\"wpforms-field-label\">Is child 4 of Hispanic\/Latinx heritage? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_96\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_96_1\" name=\"wpforms[fields][96]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_96_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_96_2\" name=\"wpforms[fields][96]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_96_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_97-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-third wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"checkbox\" data-field-id=\"97\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 4&#039;s race (please choose all that apply) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_97\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_97_1\" name=\"wpforms[fields][97][]\" value=\"Native American\/Alaskan Native\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_97_1\">Native American\/Alaskan Native<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_97_2\" name=\"wpforms[fields][97][]\" value=\"Asian\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_97_2\">Asian<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_97_3\" name=\"wpforms[fields][97][]\" value=\"African American\/Black\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_97_3\">African American\/Black<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_97_4\" name=\"wpforms[fields][97][]\" value=\"Caucasian\/White\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_97_4\">Caucasian\/White<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_97_5\" name=\"wpforms[fields][97][]\" value=\"Native Hawaiian\/Pacific Islander\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_97_5\">Native Hawaiian\/Pacific Islander<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_97_6\" name=\"wpforms[fields][97][]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_97_6\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_89-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"89\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_89\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_89\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][89]\" required><\/div><div id=\"wpforms-610-field_90-container\" class=\"wpforms-field wpforms-field-divider wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"divider\" data-field-id=\"90\" style=\"display:none;\"><h3 id=\"wpforms-610-field_90\">Child 5<\/h3><\/div><div id=\"wpforms-610-field_91-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-first wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"91\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_91\">Child 5&#039;s age <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_91\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][91]\" placeholder=\"e.g., 6 months, 4 years, 3 weeks\" required><\/div><div id=\"wpforms-610-field_92-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"92\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_92\">Child 5&#039;s gender <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_92\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][92]\" required><\/div><div id=\"wpforms-610-field_93-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"93\" style=\"display:none;\"><label class=\"wpforms-field-label\">Does child 5 live with you? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_93\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_93_1\" name=\"wpforms[fields][93]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_93_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_93_2\" name=\"wpforms[fields][93]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_93_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_94-container\" class=\"wpforms-field wpforms-field-radio wpforms-two-thirds wpforms-first wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"radio\" data-field-id=\"94\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 5&#039;s relationship to you <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_94\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_94_1\" name=\"wpforms[fields][94]\" value=\"Biological child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_94_1\">Biological child<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_94_2\" name=\"wpforms[fields][94]\" value=\"Stepchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_94_2\">Stepchild<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_94_4\" name=\"wpforms[fields][94]\" value=\"Adopted child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_94_4\">Adopted child<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_94_5\" name=\"wpforms[fields][94]\" value=\"Grandchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_94_5\">Grandchild<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_94_6\" name=\"wpforms[fields][94]\" value=\"Sibling\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_94_6\">Sibling<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_94_7\" name=\"wpforms[fields][94]\" value=\"Niece\/nephew\/cousin\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_94_7\">Niece\/nephew\/cousin<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_94_8\" name=\"wpforms[fields][94]\" value=\"Foster child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_94_8\">Foster child<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_94_9\" name=\"wpforms[fields][94]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_94_9\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_95-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"95\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_95\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_95\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][95]\" required><\/div><div id=\"wpforms-610-field_87-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-first wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"87\" style=\"display:none;\"><label class=\"wpforms-field-label\">Is child 5 of Hispanic\/Latinx heritage? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_87\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_87_1\" name=\"wpforms[fields][87]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_87_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_87_2\" name=\"wpforms[fields][87]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_87_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_88-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-third wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"checkbox\" data-field-id=\"88\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 5&#039;s race (please choose all that apply) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_88\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_88_1\" name=\"wpforms[fields][88][]\" value=\"Native American\/Alaskan Native\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_88_1\">Native American\/Alaskan Native<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_88_2\" name=\"wpforms[fields][88][]\" value=\"Asian\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_88_2\">Asian<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_88_3\" name=\"wpforms[fields][88][]\" value=\"African American\/Black\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_88_3\">African American\/Black<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_88_4\" name=\"wpforms[fields][88][]\" value=\"Caucasian\/White\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_88_4\">Caucasian\/White<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_88_5\" name=\"wpforms[fields][88][]\" value=\"Native Hawaiian\/Pacific Islander\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_88_5\">Native Hawaiian\/Pacific Islander<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_88_6\" name=\"wpforms[fields][88][]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_88_6\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_98-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"98\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_98\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_98\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][98]\" required><\/div><div id=\"wpforms-610-field_99-container\" class=\"wpforms-field wpforms-field-divider wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"divider\" data-field-id=\"99\" style=\"display:none;\"><h3 id=\"wpforms-610-field_99\">Child 6<\/h3><\/div><div id=\"wpforms-610-field_100-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-first wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"100\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_100\">Child 6&#039;s age <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_100\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][100]\" placeholder=\"e.g., 6 months, 4 years, 3 weeks\" required><\/div><div id=\"wpforms-610-field_101-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"101\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_101\">Child 6&#039;s gender <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_101\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][101]\" required><\/div><div id=\"wpforms-610-field_102-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"102\" style=\"display:none;\"><label class=\"wpforms-field-label\">Does child 6 live with you? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_102\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_102_1\" name=\"wpforms[fields][102]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_102_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_102_2\" name=\"wpforms[fields][102]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_102_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_103-container\" class=\"wpforms-field wpforms-field-radio wpforms-two-thirds wpforms-first wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"radio\" data-field-id=\"103\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 6&#039;s relationship to you <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_103\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_103_1\" name=\"wpforms[fields][103]\" value=\"Biological child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_103_1\">Biological child<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_103_2\" name=\"wpforms[fields][103]\" value=\"Stepchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_103_2\">Stepchild<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_103_4\" name=\"wpforms[fields][103]\" value=\"Adopted child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_103_4\">Adopted child<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_103_5\" name=\"wpforms[fields][103]\" value=\"Grandchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_103_5\">Grandchild<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_103_6\" name=\"wpforms[fields][103]\" value=\"Sibling\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_103_6\">Sibling<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_103_7\" name=\"wpforms[fields][103]\" value=\"Niece\/nephew\/cousin\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_103_7\">Niece\/nephew\/cousin<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_103_8\" name=\"wpforms[fields][103]\" value=\"Foster child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_103_8\">Foster child<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_103_9\" name=\"wpforms[fields][103]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_103_9\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_104-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"104\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_104\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_104\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][104]\" required><\/div><div id=\"wpforms-610-field_105-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-first wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"105\" style=\"display:none;\"><label class=\"wpforms-field-label\">Is child 6 of Hispanic\/Latinx heritage? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_105\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_105_1\" name=\"wpforms[fields][105]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_105_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_105_2\" name=\"wpforms[fields][105]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_105_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_106-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-third wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"checkbox\" data-field-id=\"106\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 6&#039;s race (please choose all that apply) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_106\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_106_1\" name=\"wpforms[fields][106][]\" value=\"Native American\/Alaskan Native\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_106_1\">Native American\/Alaskan Native<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_106_2\" name=\"wpforms[fields][106][]\" value=\"Asian\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_106_2\">Asian<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_106_3\" name=\"wpforms[fields][106][]\" value=\"African American\/Black\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_106_3\">African American\/Black<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_106_4\" name=\"wpforms[fields][106][]\" value=\"Caucasian\/White\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_106_4\">Caucasian\/White<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_106_5\" name=\"wpforms[fields][106][]\" value=\"Native Hawaiian\/Pacific Islander\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_106_5\">Native Hawaiian\/Pacific Islander<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_106_6\" name=\"wpforms[fields][106][]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_106_6\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_107-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"107\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_107\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_107\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][107]\" required><\/div><div id=\"wpforms-610-field_108-container\" class=\"wpforms-field wpforms-field-divider wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"divider\" data-field-id=\"108\" style=\"display:none;\"><h3 id=\"wpforms-610-field_108\">Child 7<\/h3><\/div><div id=\"wpforms-610-field_109-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-first wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"109\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_109\">Child 7&#039;s age <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_109\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][109]\" placeholder=\"e.g., 6 months, 4 years, 3 weeks\" required><\/div><div id=\"wpforms-610-field_110-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"110\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_110\">Child 7&#039;s gender <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_110\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][110]\" required><\/div><div id=\"wpforms-610-field_111-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"111\" style=\"display:none;\"><label class=\"wpforms-field-label\">Does child 7 live with you? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_111\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_111_1\" name=\"wpforms[fields][111]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_111_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_111_2\" name=\"wpforms[fields][111]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_111_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_112-container\" class=\"wpforms-field wpforms-field-radio wpforms-two-thirds wpforms-first wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"radio\" data-field-id=\"112\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 7&#039;s relationship to you <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_112\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_112_1\" name=\"wpforms[fields][112]\" value=\"Biological child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_112_1\">Biological child<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_112_2\" name=\"wpforms[fields][112]\" value=\"Stepchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_112_2\">Stepchild<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_112_4\" name=\"wpforms[fields][112]\" value=\"Adopted child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_112_4\">Adopted child<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_112_5\" name=\"wpforms[fields][112]\" value=\"Grandchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_112_5\">Grandchild<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_112_6\" name=\"wpforms[fields][112]\" value=\"Sibling\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_112_6\">Sibling<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_112_7\" name=\"wpforms[fields][112]\" value=\"Niece\/nephew\/cousin\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_112_7\">Niece\/nephew\/cousin<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_112_8\" name=\"wpforms[fields][112]\" value=\"Foster child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_112_8\">Foster child<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_112_9\" name=\"wpforms[fields][112]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_112_9\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_113-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"113\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_113\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_113\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][113]\" required><\/div><div id=\"wpforms-610-field_114-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-first wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"114\" style=\"display:none;\"><label class=\"wpforms-field-label\">Is child 7 of Hispanic\/Latinx heritage? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_114\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_114_1\" name=\"wpforms[fields][114]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_114_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_114_2\" name=\"wpforms[fields][114]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_114_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_115-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-third wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"checkbox\" data-field-id=\"115\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 7&#039;s race (please choose all that apply) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_115\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_115_1\" name=\"wpforms[fields][115][]\" value=\"Native American\/Alaskan Native\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_115_1\">Native American\/Alaskan Native<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_115_2\" name=\"wpforms[fields][115][]\" value=\"Asian\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_115_2\">Asian<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_115_3\" name=\"wpforms[fields][115][]\" value=\"African American\/Black\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_115_3\">African American\/Black<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_115_4\" name=\"wpforms[fields][115][]\" value=\"Caucasian\/White\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_115_4\">Caucasian\/White<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_115_5\" name=\"wpforms[fields][115][]\" value=\"Native Hawaiian\/Pacific Islander\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_115_5\">Native Hawaiian\/Pacific Islander<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_115_6\" name=\"wpforms[fields][115][]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_115_6\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_116-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"116\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_116\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_116\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][116]\" required><\/div><div id=\"wpforms-610-field_117-container\" class=\"wpforms-field wpforms-field-divider wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"divider\" data-field-id=\"117\" style=\"display:none;\"><h3 id=\"wpforms-610-field_117\">Child 8<\/h3><\/div><div id=\"wpforms-610-field_118-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-first wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"118\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_118\">Child 8&#039;s age <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_118\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][118]\" placeholder=\"e.g., 6 months, 4 years, 3 weeks\" required><\/div><div id=\"wpforms-610-field_119-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"119\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_119\">Child 8&#039;s gender <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_119\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][119]\" required><\/div><div id=\"wpforms-610-field_120-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"120\" style=\"display:none;\"><label class=\"wpforms-field-label\">Does child 8 live with you? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_120\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_120_1\" name=\"wpforms[fields][120]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_120_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_120_2\" name=\"wpforms[fields][120]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_120_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_121-container\" class=\"wpforms-field wpforms-field-radio wpforms-two-thirds wpforms-first wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"radio\" data-field-id=\"121\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 8&#039;s relationship to you <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_121\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_121_1\" name=\"wpforms[fields][121]\" value=\"Biological child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_121_1\">Biological child<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_121_2\" name=\"wpforms[fields][121]\" value=\"Stepchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_121_2\">Stepchild<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_121_4\" name=\"wpforms[fields][121]\" value=\"Adopted child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_121_4\">Adopted child<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_121_5\" name=\"wpforms[fields][121]\" value=\"Grandchild\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_121_5\">Grandchild<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_121_6\" name=\"wpforms[fields][121]\" value=\"Sibling\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_121_6\">Sibling<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_121_7\" name=\"wpforms[fields][121]\" value=\"Niece\/nephew\/cousin\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_121_7\">Niece\/nephew\/cousin<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_121_8\" name=\"wpforms[fields][121]\" value=\"Foster child\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_121_8\">Foster child<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_121_9\" name=\"wpforms[fields][121]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_121_9\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_122-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"122\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_122\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_122\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][122]\" required><\/div><div id=\"wpforms-610-field_123-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-first wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"radio\" data-field-id=\"123\" style=\"display:none;\"><label class=\"wpforms-field-label\">Is child 8 of Hispanic\/Latinx heritage? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_123\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_123_1\" name=\"wpforms[fields][123]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_123_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-610-field_123_2\" name=\"wpforms[fields][123]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_123_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_124-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-third wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-type=\"checkbox\" data-field-id=\"124\" style=\"display:none;\"><label class=\"wpforms-field-label\">Child 8&#039;s race (please choose all that apply) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-610-field_124\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_124_1\" name=\"wpforms[fields][124][]\" value=\"Native American\/Alaskan Native\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_124_1\">Native American\/Alaskan Native<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_124_2\" name=\"wpforms[fields][124][]\" value=\"Asian\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_124_2\">Asian<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_124_3\" name=\"wpforms[fields][124][]\" value=\"African American\/Black\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_124_3\">African American\/Black<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_124_4\" name=\"wpforms[fields][124][]\" value=\"Caucasian\/White\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_124_4\">Caucasian\/White<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_124_5\" name=\"wpforms[fields][124][]\" value=\"Native Hawaiian\/Pacific Islander\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_124_5\">Native Hawaiian\/Pacific Islander<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-610-field_124_6\" name=\"wpforms[fields][124][]\" value=\"Other\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-610-field_124_6\">Other<\/label><\/li><\/ul><\/div><div id=\"wpforms-610-field_125-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"125\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-610-field_125\">If other, please explain <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-610-field_125\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][125]\" required><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"610\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/research.ohioguidestone.org\/study\/wp-json\/wp\/v2\/pages\/611\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-610\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-611","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/research.ohioguidestone.org\/study\/wp-json\/wp\/v2\/pages\/611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/research.ohioguidestone.org\/study\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/research.ohioguidestone.org\/study\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/research.ohioguidestone.org\/study\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/research.ohioguidestone.org\/study\/wp-json\/wp\/v2\/comments?post=611"}],"version-history":[{"count":4,"href":"https:\/\/research.ohioguidestone.org\/study\/wp-json\/wp\/v2\/pages\/611\/revisions"}],"predecessor-version":[{"id":691,"href":"https:\/\/research.ohioguidestone.org\/study\/wp-json\/wp\/v2\/pages\/611\/revisions\/691"}],"wp:attachment":[{"href":"https:\/\/research.ohioguidestone.org\/study\/wp-json\/wp\/v2\/media?parent=611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}